{"id":7976,"date":"2020-03-06T13:07:39","date_gmt":"2020-03-06T13:07:39","guid":{"rendered":"https:\/\/www.aquasoft.de\/blog\/hilfe\/?p=7976"},"modified":"2020-06-23T10:45:17","modified_gmt":"2020-06-23T08:45:17","slug":"2d-fotos-zu-3d","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/2d-fotos-zu-3d\/","title":{"rendered":"Wie bringe ich in normale Fotos eine Illusion von 3D? &#8211; Anleitung Displacement-Mapping"},"content":{"rendered":"\n<p>In diesem Beitrag m\u00f6chte ich zeigen, wie man in Fotos einen Tunnel-Effekt bringen kann oder eine W\u00f6lbung simuliert. Das alles funktioniert mit dem Displacement-Effekt, es ist also eine Art optische T\u00e4uschung oder auch 3D-Illusion. <br>Warum man das mal ausprobieren sollte? Es ist eine perfekte Methode, um bei Betrachter ein Gef\u00fchl von &#8222;<strong>Habe ich das jetzt wirklich gesehen?<\/strong>&#8220; auszul\u00f6sen und damit Spannung zu erzeugen. Obwohl es den Effekt auch in DiaShow Ultimate gibt, gehe ich hier <strong>nur auf die Funktionsweise in <\/strong><a href=\"https:\/\/www.aquasoft.de\/stages\"><strong>Stages 11<\/strong><\/a><strong> <\/strong>ein, da hier die <strong>Einstellung \u00fcber Kurven<\/strong> sehr viel mehr M\u00f6glichkeiten bringen.<\/p>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-7ee51e66-bf09-4a94-a4de-2941ea493c2b      \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tInhalt\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#3d-illusion-w\u00f6lbung-oder-tunnel-in-fotos-bringen-mit-einer-displacement-map\" class=\"uagb-toc-link__trigger\">3D-Illusion: W\u00f6lbung oder Tunnel in Fotos bringen mit einer Displacement Map<\/a><li class=\"uagb-toc__list\"><a href=\"#wie-sage-ich-dem-bild-dass-es-sich-w\u00f6lben-oder-beugen-soll\" class=\"uagb-toc-link__trigger\">Wie sage ich dem Bild, dass es sich w\u00f6lben oder beugen soll?<\/a><li class=\"uagb-toc__list\"><a href=\"#bewegung-kommt-ins-spiel-einstellungen-im-displacement-effekt\" class=\"uagb-toc-link__trigger\">Bewegung kommt ins Spiel &#8211; Einstellungen im Displacement-Effekt<\/a><li class=\"uagb-toc__list\"><a href=\"#einstellung-\u00fcber-kurven-zur-verschiebung\" class=\"uagb-toc-link__trigger\">Einstellung \u00fcber Kurven zur Verschiebung<\/a><li class=\"uagb-toc__list\"><a href=\"#einstellung-\u00fcber-skalierung-des-verlaufs\" class=\"uagb-toc-link__trigger\">Einstellung \u00fcber Skalierung des Verlaufs<\/a><li class=\"uagb-toc__list\"><a href=\"#mit-effekten-kombinieren-oder-kamerafahrt-einf\u00fcgen-f\u00fcr-eine-echtere-3d-illusion\" class=\"uagb-toc-link__trigger\">Mit Effekten kombinieren oder Kamerafahrt einf\u00fcgen f\u00fcr eine &quot;echtere&quot; 3D-Illusion<\/a><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<p>Im starren Bild sieht man den Effekt nicht, deshalb gibt es hier gleich zu Beginn ein Beispiel-Video.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube aligncenter wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"BEISPIEL |  W\u00f6lbung oder Tunnel-Effekt mit Fotos\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/lx5u-TIzFGw?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption>Hier sieht man verschiedene Beispiele, wie man einen 3D-Effekt in normale Fotos bringen kann.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">3D-Illusion: W\u00f6lbung oder Tunnel in Fotos bringen mit einer Displacement Map <\/h2>\n\n\n\n<p>Es gibt zwei Arten von Fotos, bei denen der Effekt ganz besonders gut aussieht:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Nahaufnahmen<\/strong> im Marko-Bereich, bei denen das Motiv mittig ausgerichtet ist &#8211; hier ist eine <strong>W\u00f6lbung <\/strong>oft passend<\/li><li>Reduzierte <strong>Landschaftsaufnahmen<\/strong>, die nicht schr\u00e4g aufgenommen sind &#8211; hier passt meist ein <strong>Tunnel<\/strong><\/li><\/ul>\n\n\n\n<p>Aber wie bekommen wir jetzt die <strong>Illusion <\/strong>der W\u00f6lbung oder des Tunnels ins Foto? Dazu brauchen wir etwas, das beschreibt, wo das Foto sich ver\u00e4ndern soll &#8211; und wie stark diese Ver\u00e4nderung sein soll. Das, was wir brauchen, ist eine sogenannte <strong>Displacement-Map<\/strong>. Ein sperriger Begriff, aber wir machen es uns ganz einfach bei der Erstellung, versprochen. &#x1f60a;<\/p>\n\n\n\n<p>Unsere Displacement-Map muss noch mit dem Foto, auf das sie sich auswirken soll, verbunden werden. Das geschieht durch den Displacement-Effekt, der in der Toolbox zu finden ist. Der Effekt kann einfach auf das betreffende Foto gezogen werden. Das Foto sollte <strong>bildschirmf\u00fcllend <\/strong>und <strong>ohne Einblendung<\/strong> angezeigt werden.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/displacement-effekt-in-der-toolbox-und-in-der-timeline.jpg\" alt=\"Der Displacement-Effekt in der Toolbox und in der Timeline\" class=\"wp-image-7983\" width=\"635\" height=\"392\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/displacement-effekt-in-der-toolbox-und-in-der-timeline.jpg 847w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/displacement-effekt-in-der-toolbox-und-in-der-timeline-300x185.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/displacement-effekt-in-der-toolbox-und-in-der-timeline-768x473.jpg 768w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><figcaption>Der Displacement-Effekt liegt in der Toolbox im Tab &#8222;Objekte&#8220; unter &#8222;Live-Effekte&#8220;<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Wie sage ich dem Bild, dass es sich w\u00f6lben oder beugen soll?<\/h2>\n\n\n\n<p>Im vorherigen Abschnitt fielen ein paar mal die Worte &#8222;W\u00f6lbung&#8220; und &#8222;Tunnel&#8220;, im Beispiel am Anfang konnten wir eine Art 3D-Effekt erkennen. Wie die Displacement-Map aussehen muss, um einen bestimmten Effekt zu erzeugen, schauen wir uns jetzt mal genauer an.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"307\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/foto-mit-displacement-map-1024x307.jpg\" alt=\"Mit der Displacement-Map erh\u00e4lt das Foto der Biene sp\u00e4ter eine &quot;W\u00f6lbung&quot;\" class=\"wp-image-7985\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/foto-mit-displacement-map-1024x307.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/foto-mit-displacement-map-300x90.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/foto-mit-displacement-map-768x230.jpg 768w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/foto-mit-displacement-map.jpg 1188w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto und dazugeh\u00f6rigen Displacement-Map<\/figcaption><\/figure><\/div>\n\n\n\n<p>Die Nahaufnahme der Biene scheint sich im Beispiel-Video leicht zu bewegen, es wirkt fast so, als w\u00fcrde sich die Kamera leicht im sie herum bewegen. Durch den Displacement-Effekt hat das Bienen-Foto die Illusion einer W\u00f6lbung erhalten. Die Displacement-Map (rechtes Bild) beschreibt diese W\u00f6lbung:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Je <strong>heller <\/strong>ein Bereich in der Displacement-Map ist, desto <strong>n\u00e4her <\/strong>scheint der Bildbereich zu sein.<\/li><li>Je <strong>dunkler <\/strong>ein Bereich in der Displacement-Map ist, desto weniger wird das Foto verzerrt, der Bildbereich erscheint <strong>ferner<\/strong>.<\/li><li><strong>Schwarz <\/strong>l\u00f6st <strong>keine <\/strong>\u00c4nderung im Foto aus, alles bleibt, wie es ist.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/rechteck-dynamische-formen.jpg\" alt=\"Dynamische Form Rechteck\" class=\"wp-image-7988\" width=\"248\" height=\"218\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/rechteck-dynamische-formen.jpg 331w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/rechteck-dynamische-formen-300x264.jpg 300w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><figcaption>Rechteck aus der Toolbox<\/figcaption><\/figure><\/div>\n\n\n\n<p>In Stages 11 l\u00e4sst sich die Displacement-Map ganz einfach erzeugen. Die <strong>Dynamischen Formen<\/strong> bieten hier eine gute L\u00f6sung. Dieser Weg ist ideal f\u00fcr alle, die nicht noch in Drittsoftware herumbasteln wollen und <strong>schnell <\/strong>ein Ergebnis haben m\u00f6chten.<\/p>\n\n\n\n<p class=\"has-background has-very-light-gray-background-color\">Der Displacement-Effekt, in dem unser Foto jetzt schon liegt, hat auch einen Bereich f\u00fcr die Displacement-Map. Noch ziehen wir aber die Dynamische Form nicht hierher, sondern wir legen sie <strong>erst einmal au\u00dferhalb<\/strong> ab. So der Verlauf, den wir gleich erzeugen werden, besser sichtbar.<\/p>\n\n\n\n<p>Unter &#8222;Eigenschaften&#8220; kann man nun f\u00fcr die Dynamische Form auch einen Verlauf w\u00e4hlen. F\u00fcr unsere Tunnel\/W\u00f6lbung-Animation ben\u00f6tigen wir den <strong>kreisf\u00f6rmigen<\/strong> Verlauf.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Soll die Bildmitte nach vorne treten, muss die Mitte des Verlaufs wei\u00df sein und der \u00e4u\u00dfere Bereich schwarz. <\/li><li>Soll die Bildmitte ferner erscheinen, muss der Verlauf in der Mitte schwarz und au\u00dfen wei\u00df sein. <\/li><li>Je nachdem, wie weich der \u00dcbergang des Verlaufs ist, wird sich auch der Effekt bemerkbar machen. Ein weicher Rand ist zu Anfang meist besser.<\/li><li>Der Kreis sollte sich ungef\u00e4hr dort befinden, wo auch das Bildmotiv platziert ist. Die Position und die Gr\u00f6\u00dfe des Kreises ist \u00fcber die Schieber (Zentrum X\/Y, Skalierung) bestimmbar.<\/li><\/ul>\n\n\n\n<p>Ist der Verlauf fertig eingestellt, k\u00f6nnen wir ihn als Displacement-Map verwenden und in den Effekt ziehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bewegung kommt ins Spiel &#8211; Einstellungen im Displacement-Effekt<\/h2>\n\n\n\n<p>Jetzt haben wir die Displaement-Map, nun brauchen wir noch eine Bewegung. Dazu gibt es zwei Wege:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00fcber Kurven in den <strong>Einstellungen <\/strong>des ganzen Displacement-Effektes<\/li><li>oder in der Dynamischen Form \u00fcber die <strong>Skalierung <\/strong>mittels Kurven<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Einstellung \u00fcber Kurven zur Verschiebung<\/h2>\n\n\n\n<p>Der Displacement-Effekt hat unter &#8222;Eigenschaften&#8220; vier Schieberegler, wir widmen uns jetzt denen, die die <strong>Verschiebung (horizontal und vertikal) <\/strong>beeinflussen.<br>Um die Auswirkung einsch\u00e4tzen zu k\u00f6nnen, bewegen wir die Schieber hier nur ganz <strong>zaghaft<\/strong>. <br>Im Layoutdesigner zeigen sich so meist schon Auswirkungen. Wenn der Schieber zu stark ver\u00e4ndert wird, wirkt der Effekt auch schnell grotesk.<\/p>\n\n\n\n<p>Haben wir einen Wert gefunden, der gut passt, legen wir \u00fcber die Kurve fest, wie sich der Wert im Laufe der Zeit \u00e4ndern soll. Die Kurve kann man festlegen, indem man auf das <strong>Kurvensymbol <\/strong>unter &#8222;Eigenschaften&#8220; klickt. <br>Ich verwende gerne den gefundenen Wert und lasse die Kurve dann bis zu dessen Negativ laufen (z.B. von 3,2% zu -3,2%).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/kurve-f\u00fcr-horizontale-verschiebung.jpg\" alt=\"Horizontale Verschiebung \u00fcber die Zeit\" class=\"wp-image-7990\" width=\"480\" height=\"290\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/kurve-f\u00fcr-horizontale-verschiebung.jpg 640w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/kurve-f\u00fcr-horizontale-verschiebung-300x181.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><figcaption>Kurve f\u00fcr die Horizontale Verschiebung<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Einstellung \u00fcber Skalierung des Verlaufs<\/h2>\n\n\n\n<p>W\u00e4hrend die oben beschriebene Vorgehensweise dazu f\u00fchrt, dass die Illusion einer Bewegung entsteht, k\u00f6nnen wir auch noch einen anderen Weg gehen.<br>Hier ver\u00e4ndern wir ggf. auch die Stellung der Schieberegler im Effekt, aber nicht mithilfe einer Kurve. Der Wert bleibt <strong>fest<\/strong>.<br>Die Kurve setzen wir stattdessen an anderer Stelle ein. Dazu gehen wir zur\u00fcck in die <strong>Dynamische Form.<\/strong> Der Wert f\u00fcr die Skalierung l\u00e4sst sich hier n\u00e4mlich auch wunderbar \u00fcber die Zeit ver\u00e4ndern, wenn wir eine <strong>Kurve <\/strong>einsetzen. Wie sich das auf das Foto auswirkt, kann man ebenfalls schon im Layoutdesigner beobachten, w\u00e4hrend man den Wert \u00fcber den Schieber ver\u00e4ndert.<\/p>\n\n\n\n<p>Auch hier w\u00e4hle ich einen passenden Wert und dessen Negativ und lege so die Ver\u00e4nderung \u00fcber die Zeit fest.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mit Effekten kombinieren oder Kamerafahrt einf\u00fcgen f\u00fcr eine &#8222;echtere&#8220; 3D-Illusion<\/h2>\n\n\n\n<p>Wir haben jetzt schon eine Illusion von 3D f\u00fcr das Foto geschaffen. Man k\u00f6nnte jetzt noch Verfeinerungen einf\u00fcgen und den Effekt in eine Flexi-Collage einf\u00fcgen, um einen sanften Kameraschwenk dar\u00fcberzulegen. Auch der Weichzeichner-Effekt, ganz dezent zu Beginn eingesetzt, k\u00f6nnte noch zur Dynamik beitragen.<\/p>\n\n\n\n<p><em>Egal, wie Sie sich entscheiden, ich w\u00fcnsche Ihnen viel Spa\u00df beim Nachmachen!<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Anleitung | Cooler 3D-Effekt f\u00fcr normale Fotos \ud83e\udd29\ud83d\udcf7 (Stages 11)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gevLsUSFn2w?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n<span id=\"post-ratings-7976\" class=\"post-ratings\" data-nonce=\"f27cf33e1e\"><img decoding=\"async\" id=\"rating_7976_1\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"1 Stern\" title=\"1 Stern\" onmouseover=\"current_rating(7976, 1, '1 Stern');\" onmouseout=\"ratings_off(4.2, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_7976_2\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"2 Sterne\" title=\"2 Sterne\" onmouseover=\"current_rating(7976, 2, '2 Sterne');\" onmouseout=\"ratings_off(4.2, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_7976_3\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"3 Sterne\" title=\"3 Sterne\" onmouseover=\"current_rating(7976, 3, '3 Sterne');\" onmouseout=\"ratings_off(4.2, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_7976_4\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_on.gif\" alt=\"4 Sterne\" title=\"4 Sterne\" onmouseover=\"current_rating(7976, 4, '4 Sterne');\" onmouseout=\"ratings_off(4.2, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/><img decoding=\"async\" id=\"rating_7976_5\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/stars_crystal\/rating_off.gif\" alt=\"5 Sterne\" title=\"5 Sterne\" onmouseover=\"current_rating(7976, 5, '5 Sterne');\" onmouseout=\"ratings_off(4.2, 0, 0);\" onclick=\"rate_post();\" onkeypress=\"rate_post();\" style=\"cursor: pointer; border: 0px;\" \/> (<strong>10<\/strong> Stimmen, durchschnittlich: <strong>4,20<\/strong> von 5)<br \/><span class=\"post-ratings-text\" id=\"ratings_7976_text\"><\/span><\/span><span id=\"post-ratings-7976-loading\" class=\"post-ratings-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-content\/plugins\/wp-postratings\/images\/loading.gif\" width=\"16\" height=\"16\" class=\"post-ratings-image\" \/>Loading...<\/span>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt zwei Arten von Fotos, bei denen der Effekt ganz besonders gut aussieht:<br \/>\nNahaufnahmen im Marko-Bereich, bei denen das Motiv mittig ausgerichtet ist &#8211; hier ist eine W\u00f6lbungoft passend und<br \/>\nreduzierte Landschaftsaufnahmen, die nicht schr\u00e4g aufgenommen sind &#8211; hier passt meist ein Tunnel<\/p>\n","protected":false},"author":11,"featured_media":8001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[42,96056],"tags":[96102,92841,96101,96089],"class_list":["post-7976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-animation","category-stages-11","tag-3d","tag-displacement-effekt","tag-displacement-map","tag-dynamische-formen"],"uagb_featured_image_src":{"full":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos.jpg",1440,680,false],"thumbnail":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-150x150.jpg",150,150,true],"medium":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-300x142.jpg",300,142,true],"medium_large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-768x363.jpg",768,363,true],"large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-1024x484.jpg",1024,484,true],"1536x1536":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos.jpg",1440,680,false],"2048x2048":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos.jpg",1440,680,false],"thumb-small":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-160x160.jpg",80,80,true],"thumb-standard":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-320x320.jpg",320,320,true],"thumb-medium":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-520x245.jpg",520,245,true],"thumb-large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-720x340.jpg",720,340,true],"thumb-xlarge":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-980x450.jpg",980,450,true],"thumb-xxlarge":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos-1320x500.jpg",1320,500,true],"yarpp-thumbnail":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2020\/03\/3d-effekt-f\u00fcr-normale-fotos.jpg",120,57,false]},"uagb_author_info":{"display_name":"Nadine","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/nadine-kabelitz\/"},"uagb_comment_info":76,"uagb_excerpt":"Es gibt zwei Arten von Fotos, bei denen der Effekt ganz besonders gut aussieht: Nahaufnahmen im Marko-Bereich, bei denen das Motiv mittig ausgerichtet ist - hier ist eine W\u00f6lbungoft passend und reduzierte Landschaftsaufnahmen, die nicht schr\u00e4g aufgenommen sind - hier passt meist ein Tunnel","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/7976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=7976"}],"version-history":[{"count":19,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/7976\/revisions"}],"predecessor-version":[{"id":8646,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/7976\/revisions\/8646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media\/8001"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=7976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=7976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=7976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}