{"id":5957,"date":"2008-02-06T19:34:35","date_gmt":"2008-02-06T17:34:35","guid":{"rendered":"http:\/\/www.aquasoft.de\/blog\/?p=89"},"modified":"2008-02-06T19:34:35","modified_gmt":"2008-02-06T17:34:35","slug":"jobs-bei-aquasoft-oder-gutes-tun-und-druber-reden","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/jobs-bei-aquasoft-oder-gutes-tun-und-druber-reden\/","title":{"rendered":"Jobs bei AquaSoft oder Gutes tun und dr\u00fcber reden"},"content":{"rendered":"<p>Wieviele Fische gibt es im Meer? Niemand wei\u00df es, weil immer nur die gro\u00dfen und fetten ihre Dr(ei)ecksflosse aus dem Wasser schieben. Da\u00df auch andere, weniger bekannte, eine sch\u00f6ne Welle machen k\u00f6nnen, zeigt das Beispiel AquaSoft.<br \/>\nSeit Jahren entstehen in unserer Softwareschmiede tolle Produkte f\u00fcr Digitalkamera und Co., doch die wollen auch wahrgenommen werden. Zur Verst\u00e4rkung unserer Pr\u00e4senz in der \u00d6ffentlichkeit suchen wir daher engagierte Mitstreiter f\u00fcr die Vermarktung unserer Software auf allen relevanten Kan\u00e4len, ganz einfach dort, wo unsere Kunden zu Hause sind. Bewerbung? Nur Mut. N\u00e4heres erfahren Sie in unserer <a href=\"http:\/\/www.aquasoft.de\/Jobs.as\">Stellenanzeige<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wieviele Fische gibt es im Meer? Niemand wei\u00df es, weil immer nur die gro\u00dfen und fetten ihre Dr(ei)ecksflosse aus dem Wasser schieben. Da\u00df auch andere, weniger bekannte, eine sch\u00f6ne Welle machen k\u00f6nnen, zeigt das Beispiel AquaSoft. Seit Jahren entstehen in unserer Softwareschmiede tolle Produkte f\u00fcr Digitalkamera und Co., doch die&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[95521,92653],"tags":[],"class_list":["post-5957","post","type-post","status-publish","format-standard","hentry","category-ankundigung","category-nicht-kategorisiert"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"thumb-small":false,"thumb-standard":false,"thumb-medium":false,"thumb-large":false,"thumb-xlarge":false,"thumb-xxlarge":false,"yarpp-thumbnail":false},"uagb_author_info":{"display_name":"Steffen Binas","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/steffenbinas\/"},"uagb_comment_info":1,"uagb_excerpt":"Wieviele Fische gibt es im Meer? Niemand wei\u00df es, weil immer nur die gro\u00dfen und fetten ihre Dr(ei)ecksflosse aus dem Wasser schieben. Da\u00df auch andere, weniger bekannte, eine sch\u00f6ne Welle machen k\u00f6nnen, zeigt das Beispiel AquaSoft. Seit Jahren entstehen in unserer Softwareschmiede tolle Produkte f\u00fcr Digitalkamera und Co., doch die&#46;&#46;&#46;","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=5957"}],"version-history":[{"count":0,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5957\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=5957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=5957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=5957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}