{"id":5952,"date":"2007-07-16T13:58:57","date_gmt":"2007-07-16T11:58:57","guid":{"rendered":"http:\/\/www.aquasoft.de\/blog\/?p=79"},"modified":"2007-07-16T13:58:57","modified_gmt":"2007-07-16T11:58:57","slug":"dvd-menus-fur-mehrere-diashows","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/dvd-menus-fur-mehrere-diashows\/","title":{"rendered":"DVD-Men\u00fcs f\u00fcr mehrere Diashows"},"content":{"rendered":"<p>Mit dem <a href=\"http:\/\/diashowmanager.aquasoft.de\">DiaShow-Manager<\/a> lassen sich mehrere <a href=\"http:\/\/diashow.aquasoft.de\">Diashows<\/a> bequem auf eine DVD brennen. Die Shows werden in einem ansprechenden Men\u00fc pr\u00e4sentiert. Sogar Kapitel, die Sie in Ihren Diashows angelegt haben werden \u00fcbernommen und k\u00f6nnen direkt angesprungen werden. Es gibt etliche Men\u00fcvorlagen, die Sie frei bis ins kleinste Detail ver\u00e4ndern und anpassen k\u00f6nnen. Auch neue Vorlagen k\u00f6nnen erstellt werden.<\/p>\n<p>Die Diashows k\u00f6nnen sowohl als Video-DVD als auch als PC-Men\u00fc gebrannt werden.<\/p>\n<p>Mehr Informationen gibt es <a href=\"http:\/\/diashowmanager.aquasoft.de\">hier&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem DiaShow-Manager lassen sich mehrere Diashows bequem auf eine DVD brennen. Die Shows werden in einem ansprechenden Men\u00fc pr\u00e4sentiert. Sogar Kapitel, die Sie in Ihren Diashows angelegt haben werden \u00fcbernommen und k\u00f6nnen direkt angesprungen werden. Es gibt etliche Men\u00fcvorlagen, die Sie frei bis ins kleinste Detail ver\u00e4ndern und anpassen&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[95521,92418,92653],"tags":[],"class_list":["post-5952","post","type-post","status-publish","format-standard","hentry","category-ankundigung","category-diashow","category-nicht-kategorisiert"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"thumb-small":false,"thumb-standard":false,"thumb-medium":false,"thumb-large":false,"thumb-xlarge":false,"thumb-xxlarge":false,"yarpp-thumbnail":false},"uagb_author_info":{"display_name":"Steffen Binas","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/steffenbinas\/"},"uagb_comment_info":0,"uagb_excerpt":"Mit dem DiaShow-Manager lassen sich mehrere Diashows bequem auf eine DVD brennen. Die Shows werden in einem ansprechenden Men\u00fc pr\u00e4sentiert. Sogar Kapitel, die Sie in Ihren Diashows angelegt haben werden \u00fcbernommen und k\u00f6nnen direkt angesprungen werden. Es gibt etliche Men\u00fcvorlagen, die Sie frei bis ins kleinste Detail ver\u00e4ndern und anpassen&#46;&#46;&#46;","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=5952"}],"version-history":[{"count":0,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5952\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=5952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=5952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=5952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}