{"id":5947,"date":"2007-03-29T18:46:39","date_gmt":"2007-03-29T16:46:39","guid":{"rendered":"http:\/\/www.aquasoft.de\/blog\/?p=72"},"modified":"2007-03-29T18:46:39","modified_gmt":"2007-03-29T16:46:39","slug":"discmenu-startmenus-fur-cddvd-publikationen","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/discmenu-startmenus-fur-cddvd-publikationen\/","title":{"rendered":"DiscMenu &#8211; Startmen\u00fcs f\u00fcr CD\/DVD-Publikationen"},"content":{"rendered":"<p><img decoding=\"async\" align=\"right\" alt=\"discmenubox.jpg\" id=\"image73\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2007\/03\/discmenubox.jpg\" \/>Mit <a href=\"http:\/\/www.discmenu.de\">DiscMenu 2<\/a> haben wir heute ein neues Programm ver\u00f6ffentlicht. Dieses Programm macht sich die Gestaltungsm\u00f6glichkeiten von HTML-Seiten zu Nutze, um daraus Startmen\u00fcs f\u00fcr CDs und DVDs zu erstellen. Es sorgt daf\u00fcr, dass verlinkte Programme und Dokumente gleich gestartet werden, und nicht wie vom Webbrowser \u00fcblich, heruntergeladen werden. Dazu gibt es noch weitere Steuerm\u00f6glichkeiten, die in die Men\u00fcseiten eingebaut werden k\u00f6nnen.<\/p>\n<p>Nat\u00fcrlich haben wir auch an die <a href=\"http:\/\/diashow.aquasoft.de\">DiaShow<\/a> gedacht. Trifft DiscMenu auf eine Diashow (ADS-Datei), wird diese automatisch mit dem DiaShow-Player gestartet. Auf diese Weise lassen sich CDs erstellen, von denen aus mehrere Diashows \u00fcber ein bequemes Men\u00fc abgespielt werden k\u00f6nnen.<\/p>\n<p>Wo ist Version 1? Diese Version ist bereits vor Jahren intern bei uns im Einsatz gewesen, erst Version 2 hat es nun bis in die \u00d6ffentlichkeit geschafft.<\/p>\n<p>Alle Informationen zu DiscMenu gibt es unter <a href=\"http:\/\/www.discmenu.de\">www.discmenu.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit DiscMenu 2 haben wir heute ein neues Programm ver\u00f6ffentlicht. Dieses Programm macht sich die Gestaltungsm\u00f6glichkeiten von HTML-Seiten zu Nutze, um daraus Startmen\u00fcs f\u00fcr CDs und DVDs zu erstellen. Es sorgt daf\u00fcr, dass verlinkte Programme und Dokumente gleich gestartet werden, und nicht wie vom Webbrowser \u00fcblich, heruntergeladen werden. Dazu gibt&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[95521,92653],"tags":[],"class_list":["post-5947","post","type-post","status-publish","format-standard","hentry","category-ankundigung","category-nicht-kategorisiert"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"thumb-small":false,"thumb-standard":false,"thumb-medium":false,"thumb-large":false,"thumb-xlarge":false,"thumb-xxlarge":false,"yarpp-thumbnail":false},"uagb_author_info":{"display_name":"Steffen Binas","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/steffenbinas\/"},"uagb_comment_info":0,"uagb_excerpt":"Mit DiscMenu 2 haben wir heute ein neues Programm ver\u00f6ffentlicht. Dieses Programm macht sich die Gestaltungsm\u00f6glichkeiten von HTML-Seiten zu Nutze, um daraus Startmen\u00fcs f\u00fcr CDs und DVDs zu erstellen. Es sorgt daf\u00fcr, dass verlinkte Programme und Dokumente gleich gestartet werden, und nicht wie vom Webbrowser \u00fcblich, heruntergeladen werden. Dazu gibt&#46;&#46;&#46;","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=5947"}],"version-history":[{"count":0,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/5947\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=5947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=5947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=5947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}