{"id":3822,"date":"2016-10-02T17:55:21","date_gmt":"2016-10-02T17:55:21","guid":{"rendered":"http:\/\/www.aquasoft.de\/blog\/hilfe\/?p=3822"},"modified":"2016-10-10T09:00:03","modified_gmt":"2016-10-10T09:00:03","slug":"was-ist-eine-asimage-datei","status":"publish","type":"post","link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/was-ist-eine-asimage-datei\/","title":{"rendered":"Was ist eine asimage-Datei?"},"content":{"rendered":"<p>Im Zusammenhang mit AquaSoft DiaShow und Stages begegnen Ihnen Dateiendungen wie <a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/ads-datei\/\">*.ads<\/a>, *.aso und <strong>*.asimage<\/strong>. In unserem Demo-Projekt, das Sie sich in Version 10 ansehen k\u00f6nnen (&#8222;Datei&#8220; &#8211; &#8222;\u00d6ffnen&#8220; &#8211; &#8222;Beispielprojekt&#8230;&#8220;) , befinden sich viele Dateien mit der Endung &#8222;*.asimage&#8220; und im<a href=\"http:\/\/forum.aquasoft.de\/viewtopic.php?f=50&amp;p=103853&amp;sid=15d2db41cb146a58e32f52f2ce69af96\"> AquaSoft-Forum<\/a> kam daher k\u00fcrzlich die Frage auf, was das bedeutet.<br \/>\nIn diesem Beitrag erfahren Sie, was es mit der asimage-Datei auf sich hat, wie sie entsteht und was Sie damit machen k\u00f6nnen.<!--more--><\/p>\n<h2>Was ist eine asimage-Datei?<\/h2>\n<p>Sie erstellen ein Projekt und m\u00f6chten es an jemanden weitergeben, der das Programm nicht installiert hat &#8211; das geht mit Hilfe des <a href=\"http:\/\/www.aquasoft.de\/help\/diashow10\/pc-show.htm\">Archivierungs-Assistenten<\/a>. Sie k\u00f6nnen mit dem Archivierungs-Assistenten eine Datei f\u00fcr den Player exportieren, der Ihr Projekt genauso wiedergibt, wie Sie es erstellt haben. Das Sch\u00f6ne ist, dass man hier &#8211; im Gegensatz zu einem Video &#8211; viel mehr M\u00f6glichkeiten zur <a href=\"http:\/\/www.aquasoft.de\/help\/diashow10\/manuelle_steuerung.htm\">manuellen Steuerung<\/a> hat. Aber nicht nur der Player wird mitgeliefert, sondern auch <strong>alle Bilder, die zu Ihrem Projekt geh\u00f6ren<\/strong>. In manchen F\u00e4llen ist das nicht w\u00fcnschenswert oder sogar problematisch (wenn es z.B. urheberrechtlich gesch\u00fctzte Bilder sind).<\/p>\n<p>In DiaShow 10 Ultimate und Stages 10 haben Sie die M\u00f6glichkeit, Ihre Bilder zu sch\u00fctzen, sodass sie nur innerhalb der Software angezeigt werden k\u00f6nnen.<\/p>\n<div id=\"attachment_4545\" style=\"width: 505px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/bilder-sch\u00fctzen-asimage-aquasoft.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4545\" class=\" wp-image-4545\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/bilder-sch\u00fctzen-asimage-aquasoft.jpg\" alt=\"Bilder sch\u00fctzen im Archivierungs-Assistenten\" width=\"495\" height=\"328\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/bilder-sch\u00fctzen-asimage-aquasoft.jpg 933w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/bilder-sch\u00fctzen-asimage-aquasoft-300x199.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/bilder-sch\u00fctzen-asimage-aquasoft-768x509.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/a><p id=\"caption-attachment-4545\" class=\"wp-caption-text\">Bilder sch\u00fctzen im Archivierungs-Assistenten<\/p><\/div>\n<p>In DiaShow 10 Ultimate k\u00f6nnen Sie nur Ihre Bilder verschl\u00fcsseln. In <a href=\"http:\/\/www.aquasoft.de\/stages\">Stages 10<\/a> k\u00f6nnen Sie au\u00dferdem<\/p>\n<ul>\n<li>Bilder an das exportierte Projekt koppeln &#8211; d.h. die Bilder k\u00f6nnen nur innerhalb des Projektes verwendet werden, sonst an keiner anderen Stelle<\/li>\n<li>Das ganze Projekt nur noch abspielbar machen &#8211; man kann es dann nicht mehr bearbeiten<\/li>\n<li>Das Projekt mit einem Passwort sch\u00fctzen, das vor dem \u00d6ffnen oder Abspielen abgefragt wird<\/li>\n<\/ul>\n<p>Die verschl\u00fcsselten Bilder haben nicht mehr die Dateiendung *.jpg oder *.png. Sie behalten ihren Dateinamen, haben jetzt aber die Dateiendnung *.asimage. Das sehen Sie auch im archivierten Ordner und im Dateipfad, der im Projekt angezeigt wird.<br \/>\n<a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4546\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei.jpg\" alt=\"asimage-datei\" width=\"800\" height=\"70\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei.jpg 800w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-300x26.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-768x67.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<h2>Wie erstelle ich eine asimage-Datei?<\/h2>\n<p>Eine asimage-Datei k\u00f6nnen Sie nur mit Hilfe des Archivierungs-Assistenten erstellen. Dieser verschl\u00fcsselt Ihre Bilder dann auf einem speziellen Weg, den man nicht nachstellen kann und der auch nicht r\u00fcckg\u00e4ngig gemacht werden kann. Das bedeutet, dass man die asimage-Datei nicht einfach in einen anderen Dateityp konvertieren kann. Damit k\u00f6nnen Sie ziemlich sicher sein, dass Ihre Bilder gesch\u00fctzt sind.<\/p>\n<p>Andererseits sollten Sie unbedingt darauf achten, dass Sie die <strong>Originalbilder nicht l\u00f6schen<\/strong>. Wenn diese weg w\u00e4ren und Sie nur noch die asimage-Dateien h\u00e4tten, k\u00f6nnten Sie damit nichts mehr au\u00dferhalb von AquaSoft-Programmen anfangen.<a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-nicht-konvertieren.jpg\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4556 aligncenter\" src=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-nicht-konvertieren-1024x761.jpg\" alt=\"asimage-Dateien lassen sich nicht konvertieren\" width=\"494\" height=\"367\" srcset=\"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-nicht-konvertieren-1024x761.jpg 1024w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-nicht-konvertieren-300x223.jpg 300w, https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-nicht-konvertieren-768x571.jpg 768w\" sizes=\"auto, (max-width: 494px) 100vw, 494px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>Wie kann ich die asimage-Datei verwenden?<\/h2>\n<p>Wenn eine asimage-Datei an das Projekt gekoppelt ist, mit dem sie erstellt wurde, k\u00f6nnen Sie die Datei h\u00f6chstens l\u00f6schen oder innerhalb des Projektes bearbeiten. Wenn die Datei nicht an das Projekt gekoppelt ist, sind Sie etwas freier. Sie k\u00f6nnen die Datei, wie andere Dateien auch, per Drag&amp;Drop in ein anderes Projekt einf\u00fcgen und ganz normal damit arbeiten. Was in beiden F\u00e4llen definitiv nicht geht, ist das \u00d6ffnen in anderen Programmen. Sie k\u00f6nnen das Bild also nicht in Photoshop weiter bearbeiten, beim Fotodienst ausdrucken lassen und auch, wenn Sie es jemanden per <a href=\"https:\/\/www.aquasoft.de\/blog\/hilfe\/diashow-versenden-per-e-mail-und-alternativen\/\">E-Mail<\/a> senden, wird der Empf\u00e4nger es nicht \u00f6ffnen k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Zusammenhang mit AquaSoft DiaShow und Stages begegnen Ihnen Dateiendungen wie *.ads, *.aso und *.asimage. In unserem Demo-Projekt, das Sie sich in Version 10 ansehen k\u00f6nnen (&#8222;Datei&#8220; &#8211; &#8222;\u00d6ffnen&#8220; &#8211; &#8222;Beispielprojekt&#8230;&#8220;) , befinden sich viele Dateien mit der Endung &#8222;*.asimage&#8220; und im AquaSoft-Forum kam daher k\u00fcrzlich die Frage auf, was&#46;&#46;&#46;<\/p>\n","protected":false},"author":11,"featured_media":4549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[92416],"tags":[92473,94372,95428,95427,95429,95430],"class_list":["post-3822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diashow-exportieren","tag-ads","tag-archivieren","tag-asimage","tag-aso","tag-schuetzen","tag-verschluesseln"],"uagb_featured_image_src":{"full":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung.jpg",1440,680,false],"thumbnail":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-150x150.jpg",150,150,true],"medium":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-300x142.jpg",300,142,true],"medium_large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-768x363.jpg",768,363,true],"large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-1024x484.jpg",1024,484,true],"1536x1536":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung.jpg",1440,680,false],"2048x2048":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung.jpg",1440,680,false],"thumb-small":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-160x160.jpg",80,80,true],"thumb-standard":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-320x320.jpg",320,320,true],"thumb-medium":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-520x245.jpg",520,245,true],"thumb-large":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung-720x340.jpg",720,340,true],"thumb-xlarge":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung.jpg",953,450,false],"thumb-xxlarge":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung.jpg",1059,500,false],"yarpp-thumbnail":["https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/files\/2016\/09\/asimage-datei-endung.jpg",120,57,false]},"uagb_author_info":{"display_name":"Nadine","author_link":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/author\/nadine-kabelitz\/"},"uagb_comment_info":0,"uagb_excerpt":"Im Zusammenhang mit AquaSoft DiaShow und Stages begegnen Ihnen Dateiendungen wie *.ads, *.aso und *.asimage. In unserem Demo-Projekt, das Sie sich in Version 10 ansehen k\u00f6nnen (&#8222;Datei&#8220; &#8211; &#8222;\u00d6ffnen&#8220; &#8211; &#8222;Beispielprojekt&#8230;&#8220;) , befinden sich viele Dateien mit der Endung &#8222;*.asimage&#8220; und im AquaSoft-Forum kam daher k\u00fcrzlich die Frage auf, was&#46;&#46;&#46;","_links":{"self":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/3822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/comments?post=3822"}],"version-history":[{"count":15,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/3822\/revisions"}],"predecessor-version":[{"id":4807,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/posts\/3822\/revisions\/4807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media\/4549"}],"wp:attachment":[{"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/media?parent=3822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/categories?post=3822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogneu.aquasoft.de\/blog\/hilfe\/wp-json\/wp\/v2\/tags?post=3822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}